{"id":3657,"date":"2023-10-04T10:40:59","date_gmt":"2023-10-04T08:40:59","guid":{"rendered":"https:\/\/natuurhuisjezweden.nl\/berghuis-hoegrun\/"},"modified":"2023-11-08T14:24:22","modified_gmt":"2023-11-08T13:24:22","slug":"berghuis-hoegrun","status":"publish","type":"page","link":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/","title":{"rendered":"Berghuis H\u00f6grun"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3657\" class=\"elementor elementor-3657 elementor-1517\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b3d00fe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6b3d00fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9017e8\" data-id=\"9017e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53d6191e elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"53d6191e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220604_181520.jpg\" alt=\"20220604_181520\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_152715.jpg\" alt=\"20220930_152715\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_152753.jpg\" alt=\"20220930_152753\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_152811.jpg\" alt=\"20220930_152811\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_152830.jpg\" alt=\"20220930_152830\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_152844.jpg\" alt=\"20220930_152844\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_154037.jpg\" alt=\"20220930_154037\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_155042.jpg\" alt=\"20220930_155042\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_175430.jpg\" alt=\"20220930_175430\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_175635.jpg\" alt=\"20220930_175635\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20220930_184948.jpg\" alt=\"20220930_184948\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20221110_111327.jpg\" alt=\"20221110_111327\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20230119_194918.jpg\" alt=\"20230119_194918\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20230119_195214.jpg\" alt=\"20230119_195214\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/IMG-20230227-WA0002.jpg\" alt=\"IMG-20230227-WA0002\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 von 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/IMG-20230923-WA0000.jpg\" alt=\"IMG-20230923-WA0000\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae3d82d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae3d82d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1350ede1\" data-id=\"1350ede1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf37c55 elementor-widget elementor-widget-text-editor\" data-id=\"bf37c55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dieses Haus verf\u00fcgt \u00fcber ein Wohnzimmer, eine K\u00fcche, ein Esszimmer, einen Flur, ein Badezimmer mit Dusche und WC, eine Sauna, ein Schlafzimmer mit Doppelbett, ein Schlafzimmer mit Etagenbett und einen Dachboden mit Doppelbett und Sitzecke. Drau\u00dfen gibt es eine Terrasse, einen Schuppen und viel Platz um das Haus herum.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bbf6b5 elementor-align-left elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"9bbf6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/airbnb.com\/h\/onrun\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-airbnb\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt auf airbnb buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a68750d elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a68750d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:20,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4763c25b jkit-sticky-element--enabled jkit-sticky-element-on--down jkit-sticky-position--sticky\" data-id=\"4763c25b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jkit_sticky_device&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;jkit_sticky_top_position&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]}}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-647ad877 elementor-widget elementor-widget-heading\" data-id=\"647ad877\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unterkunft buchen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4222f8d2 elementor-widget elementor-widget-text-editor\" data-id=\"4222f8d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entdecken Sie Schwedens bezaubernde Naturh\u00fctten und buchen Sie \u00fcber Airbnb einen unvergesslichen Aufenthalt inmitten der atemberaubenden schwedischen Wildnis. Klicken Sie hier, um Ihre Reise zu Frieden und Abenteuer zu beginnen!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ed720 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"f7ed720\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/airbnb.com\/h\/onrun\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-airbnb\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt auf airbnb buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c8fece2 jkit-sticky-element--enabled jkit-sticky-element-on--down jkit-sticky-position--sticky\" data-id=\"2c8fece2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jkit_sticky_device&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;jkit_sticky_top_position&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]}}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e65a9a9 elementor-widget elementor-widget-heading\" data-id=\"e65a9a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vollst\u00e4ndig ausgestattet<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dee16d9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7dee16d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Geeignet f\u00fcr 6 Personen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kamin<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Au\u00dfenterrasse<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Badezimmer mit Dusche und Toilette<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sauna<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">K\u00fcche mit Herd, K\u00fchl- und Gefrierschrank, u.a.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wi-Fi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Smart TV<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-check-circle-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ausreichend Parkpl\u00e4tze<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bef3012 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2bef3012\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/airbnb.com\/h\/onrun\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-external-link-alt-solid\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Siehe alle Annehmlichkeiten auf airbnb<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42799fc6 elementor-widget elementor-widget-spacer\" data-id=\"42799fc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-363ee212 elementor-widget elementor-widget-heading\" data-id=\"363ee212\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Standort \u00d6nrun<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad21b27 elementor-widget elementor-widget-google_maps\" data-id=\"4ad21b27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Onrun&#038;t=m&#038;z=6&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Onrun\"\n\t\t\t\t\taria-label=\"Onrun\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39f97ecd elementor-widget elementor-widget-spacer\" data-id=\"39f97ecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c6f6e7b elementor-widget elementor-widget-heading\" data-id=\"4c6f6e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Was unsere G\u00e4ste sagen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638d4df9 elementor-review--has-separator elementor--star-style-star_fontawesome elementor-widget elementor-widget-reviews\" data-id=\"638d4df9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"reviews.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-5f69710\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/09\/airbnb_logo_icon_170605.png\" alt=\"Ma\u0142gorzata\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Ma\u0142gorzata<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Weiterlesen\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tSehr friedlicher und ruhiger Ort\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial elementor-repeater-item-3a1a8df\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__header\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/09\/airbnb_logo_icon_170605.png\" alt=\"G\u00f6ran\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">G\u00f6ran<\/span><\/cite>\t\t\t\t\t<div class=\"elementor-testimonial__icon elementor-icon elementor-icon-\" aria-label=\"Weiterlesen\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tHolzhaus mit sehr hohem Standard zu einem \u00fcberraschend niedrigen Preis\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78616871 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78616871\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6998e40e\" data-id=\"6998e40e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-186deff6 elementor-widget elementor-widget-heading\" data-id=\"186deff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erlebe dein Schweden-Abenteuer!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1453f456 elementor-widget elementor-widget-text-editor\" data-id=\"1453f456\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ergreifen Sie Ihre Chance und fahren Sie zum Ans\u00e4ttfj\u00e4llen in J\u00e4mtland, wo die Entspannung und der Genuss der beeindruckenden Wildnis sofort beginnen. Hier treffen Sie auf das Echte und Authentische!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4e3a32 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2d4e3a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/natuurhuisjezweden.nl\/de\/umgebung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Erkunden Sie die Umgebung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23d0aa3d elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23d0aa3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38f35cb2\" data-id=\"38f35cb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aadc054 elementor-widget elementor-widget-heading\" data-id=\"3aadc054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unterkunft buchen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-532d876 elementor-widget elementor-widget-text-editor\" data-id=\"532d876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entdecken Sie Schwedens bezaubernde Naturh\u00fctten und buchen Sie \u00fcber Airbnb einen unvergesslichen Aufenthalt inmitten der atemberaubenden schwedischen Wildnis. Klicken Sie hier, um Ihre Reise zu Frieden und Abenteuer zu beginnen!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64ebddf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"64ebddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/airbnb.com\/h\/onrun\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-airbnb\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt auf airbnb buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dieses Haus verf\u00fcgt \u00fcber ein Wohnzimmer, eine K\u00fcche, ein Esszimmer, einen Flur, ein Badezimmer mit Dusche und WC, eine Sauna, ein Schlafzimmer mit Doppelbett, ein Schlafzimmer mit Etagenbett und einen Dachboden mit Doppelbett und Sitzecke. Drau\u00dfen gibt es eine Terrasse, einen Schuppen und viel Platz um das Haus herum. Jetzt auf airbnb buchen Unterkunft buchen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3440,"parent":3699,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3657","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>%<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"%\" \/>\n<meta property=\"og:description\" content=\"Dieses Haus verf\u00fcgt \u00fcber ein Wohnzimmer, eine K\u00fcche, ein Esszimmer, einen Flur, ein Badezimmer mit Dusche und WC, eine Sauna, ein Schlafzimmer mit Doppelbett, ein Schlafzimmer mit Etagenbett und einen Dachboden mit Doppelbett und Sitzecke. Drau\u00dfen gibt es eine Terrasse, einen Schuppen und viel Platz um das Haus herum. Jetzt auf airbnb buchen Unterkunft buchen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/\" \/>\n<meta property=\"og:site_name\" content=\"Naturfreundehaus Schweden\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/natuurhuisjezweden\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T13:24:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20221110_111327.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/\",\"url\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/\",\"name\":\"%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/20221110_111327.jpg\",\"datePublished\":\"2023-10-04T08:40:59+00:00\",\"dateModified\":\"2023-11-08T13:24:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/#primaryimage\",\"url\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/20221110_111327.jpg\",\"contentUrl\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/20221110_111327.jpg\",\"width\":1280,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/bleiben-sie\\\/oenrun\\\/berghuis-hoegrun\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bleiben Sie\",\"item\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/verblijf\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00d6nrun\",\"item\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/verblijf\\\/onrun\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Berghuis H\u00f6grun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/\",\"name\":\"Natuurhuisje Zweden\",\"description\":\"Buchen Sie Ihr Schweden-Abenteuer\",\"publisher\":{\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/#organization\",\"name\":\"Naturfreundehaus Schweden\",\"url\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Natuurhuisje-zweden-logo-nieuw.png\",\"contentUrl\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Natuurhuisje-zweden-logo-nieuw.png\",\"width\":454,\"height\":375,\"caption\":\"Naturfreundehaus Schweden\"},\"image\":{\"@id\":\"https:\\\/\\\/natuurhuisjezweden.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/natuurhuisjezweden\\\/\",\"https:\\\/\\\/www.instagram.com\\\/natuurhuisjezweden\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/","og_locale":"de_DE","og_type":"article","og_title":"%","og_description":"Dieses Haus verf\u00fcgt \u00fcber ein Wohnzimmer, eine K\u00fcche, ein Esszimmer, einen Flur, ein Badezimmer mit Dusche und WC, eine Sauna, ein Schlafzimmer mit Doppelbett, ein Schlafzimmer mit Etagenbett und einen Dachboden mit Doppelbett und Sitzecke. Drau\u00dfen gibt es eine Terrasse, einen Schuppen und viel Platz um das Haus herum. Jetzt auf airbnb buchen Unterkunft buchen [&hellip;]","og_url":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/","og_site_name":"Naturfreundehaus Schweden","article_publisher":"https:\/\/www.facebook.com\/natuurhuisjezweden\/","article_modified_time":"2023-11-08T13:24:22+00:00","og_image":[{"width":1280,"height":1707,"url":"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20221110_111327.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/","url":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/","name":"%","isPartOf":{"@id":"https:\/\/natuurhuisjezweden.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/#primaryimage"},"image":{"@id":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/#primaryimage"},"thumbnailUrl":"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20221110_111327.jpg","datePublished":"2023-10-04T08:40:59+00:00","dateModified":"2023-11-08T13:24:22+00:00","breadcrumb":{"@id":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/#primaryimage","url":"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20221110_111327.jpg","contentUrl":"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/20221110_111327.jpg","width":1280,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/natuurhuisjezweden.nl\/de\/bleiben-sie\/oenrun\/berghuis-hoegrun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/natuurhuisjezweden.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Bleiben Sie","item":"https:\/\/natuurhuisjezweden.nl\/de\/verblijf\/"},{"@type":"ListItem","position":3,"name":"\u00d6nrun","item":"https:\/\/natuurhuisjezweden.nl\/de\/verblijf\/onrun\/"},{"@type":"ListItem","position":4,"name":"Berghuis H\u00f6grun"}]},{"@type":"WebSite","@id":"https:\/\/natuurhuisjezweden.nl\/de\/#website","url":"https:\/\/natuurhuisjezweden.nl\/de\/","name":"Natuurhuisje Zweden","description":"Buchen Sie Ihr Schweden-Abenteuer","publisher":{"@id":"https:\/\/natuurhuisjezweden.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/natuurhuisjezweden.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/natuurhuisjezweden.nl\/de\/#organization","name":"Naturfreundehaus Schweden","url":"https:\/\/natuurhuisjezweden.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/natuurhuisjezweden.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/Natuurhuisje-zweden-logo-nieuw.png","contentUrl":"https:\/\/natuurhuisjezweden.nl\/wp-content\/uploads\/2023\/10\/Natuurhuisje-zweden-logo-nieuw.png","width":454,"height":375,"caption":"Naturfreundehaus Schweden"},"image":{"@id":"https:\/\/natuurhuisjezweden.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/natuurhuisjezweden\/","https:\/\/www.instagram.com\/natuurhuisjezweden\/"]}]}},"_links":{"self":[{"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/pages\/3657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/comments?post=3657"}],"version-history":[{"count":4,"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/pages\/3657\/revisions"}],"predecessor-version":[{"id":3925,"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/pages\/3657\/revisions\/3925"}],"up":[{"embeddable":true,"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/pages\/3699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/media\/3440"}],"wp:attachment":[{"href":"https:\/\/natuurhuisjezweden.nl\/de\/wp-json\/wp\/v2\/media?parent=3657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}